{"id":1464,"date":"2017-12-21T17:21:44","date_gmt":"2017-12-21T17:21:44","guid":{"rendered":"http:\/\/localhost:10151\/?p=1464"},"modified":"2017-12-22T20:54:39","modified_gmt":"2017-12-22T20:54:39","slug":"del-monte-names-um-philippines-media-aor","status":"publish","type":"post","link":"https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/","title":{"rendered":"Del Monte Names UM Philippines Media AOR"},"content":{"rendered":"<p>IPG Mediabrands\u00a0the global media arm of Interpublic Group (NYSE: IPG), has today announced UM\u2019s appointment as media AOR for Del Monte, the branded food and beverage production and distribution company. The announcement follows a competitive pitch which included Del Monte\u2019s two incumbent agencies.<\/p>\n<p>Selected for the originality and creativity for their insights and strategies bolstered by their strength in trading, UM Philippines has been awarded the full portfolio of the Del Monte business including media, digital, and on-ground.<\/p>\n<p>Venus Navalta, IPG Mediabrands Philippines CEO commented, \u201cAt UM we use better science, to drive better art, and better outcomes. Our insights were anchored in solid data. We use advanced marketing analytics to power our recommendations, ensuring we can deliver the business results to give Del Monte a competitive advantage.\u201d<\/p>\n<p><a href=\"http:\/\/www.adobomagazine.com\/philippine-news\/del-monte-names-um-philippines-aor\" target=\"_blank\" rel=\"noopener\">Read the full story<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>UM Philippines has been named media AOR for Del Monte, the branded food and beverage production and distribution company.<\/p>\n","protected":false},"author":44,"featured_media":1488,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-um-in-the-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Del Monte Names UM Philippines Media AOR - UM JAPAN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Del Monte Names UM Philippines Media AOR - UM JAPAN\" \/>\n<meta property=\"og:description\" content=\"UM Philippines has been named media AOR for Del Monte, the branded food and beverage production and distribution company.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/\" \/>\n<meta property=\"og:site_name\" content=\"UM JAPAN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UMCuriosity\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-21T17:21:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-22T20:54:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jp.umww.com\/wp-content\/uploads\/2017\/12\/del-monte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"shajibur.rahman@interpublic.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@UMWorldwide\" \/>\n<meta name=\"twitter:site\" content=\"@UMWorldwide\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"shajibur.rahman@interpublic.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/um-in-the-news\\\/del-monte-names-um-philippines-media-aor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/um-in-the-news\\\/del-monte-names-um-philippines-media-aor\\\/\"},\"author\":{\"name\":\"shajibur.rahman@interpublic.com\",\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/#\\\/schema\\\/person\\\/3ab450da4e035a60341554a2a939596c\"},\"headline\":\"Del Monte Names UM Philippines Media AOR\",\"datePublished\":\"2017-12-21T17:21:44+00:00\",\"dateModified\":\"2017-12-22T20:54:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/um-in-the-news\\\/del-monte-names-um-philippines-media-aor\\\/\"},\"wordCount\":142,\"publisher\":{\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/um-in-the-news\\\/del-monte-names-um-philippines-media-aor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jp.umww.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/del-monte.jpg\",\"articleSection\":[\"UM in the News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/um-in-the-news\\\/del-monte-names-um-philippines-media-aor\\\/\",\"url\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/um-in-the-news\\\/del-monte-names-um-philippines-media-aor\\\/\",\"name\":\"Del Monte Names UM Philippines Media AOR - UM JAPAN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/um-in-the-news\\\/del-monte-names-um-philippines-media-aor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/um-in-the-news\\\/del-monte-names-um-philippines-media-aor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jp.umww.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/del-monte.jpg\",\"datePublished\":\"2017-12-21T17:21:44+00:00\",\"dateModified\":\"2017-12-22T20:54:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/um-in-the-news\\\/del-monte-names-um-philippines-media-aor\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jp.umww.com\\\/en\\\/um-in-the-news\\\/del-monte-names-um-philippines-media-aor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/um-in-the-news\\\/del-monte-names-um-philippines-media-aor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jp.umww.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/del-monte.jpg\",\"contentUrl\":\"https:\\\/\\\/jp.umww.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/del-monte.jpg\",\"width\":1500,\"height\":844},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/um-in-the-news\\\/del-monte-names-um-philippines-media-aor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Del Monte Names UM Philippines Media AOR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/\",\"name\":\"UM JAPAN\",\"description\":\"UM is a global media company.\",\"publisher\":{\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/#organization\",\"name\":\"UM\",\"url\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/jp.umww.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/um-logo-transparent.png\",\"contentUrl\":\"http:\\\/\\\/jp.umww.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/um-logo-transparent.png\",\"width\":1378,\"height\":1378,\"caption\":\"UM\"},\"image\":{\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UMCuriosity\",\"https:\\\/\\\/x.com\\\/UMWorldwide\",\"https:\\\/\\\/www.instagram.com\\\/umworldwide\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/um-ww\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jp.umww.com\\\/en\\\/#\\\/schema\\\/person\\\/3ab450da4e035a60341554a2a939596c\",\"name\":\"shajibur.rahman@interpublic.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c53087da78d35d0574c041797fcd515f7503127068cd135b670ef31b05d4c151?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c53087da78d35d0574c041797fcd515f7503127068cd135b670ef31b05d4c151?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c53087da78d35d0574c041797fcd515f7503127068cd135b670ef31b05d4c151?s=96&d=mm&r=g\",\"caption\":\"shajibur.rahman@interpublic.com\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Del Monte Names UM Philippines Media AOR - UM JAPAN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/","og_locale":"en_US","og_type":"article","og_title":"Del Monte Names UM Philippines Media AOR - UM JAPAN","og_description":"UM Philippines has been named media AOR for Del Monte, the branded food and beverage production and distribution company.","og_url":"https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/","og_site_name":"UM JAPAN","article_publisher":"https:\/\/www.facebook.com\/UMCuriosity","article_published_time":"2017-12-21T17:21:44+00:00","article_modified_time":"2017-12-22T20:54:39+00:00","og_image":[{"width":1500,"height":844,"url":"https:\/\/jp.umww.com\/wp-content\/uploads\/2017\/12\/del-monte.jpg","type":"image\/jpeg"}],"author":"shajibur.rahman@interpublic.com","twitter_card":"summary_large_image","twitter_creator":"@UMWorldwide","twitter_site":"@UMWorldwide","twitter_misc":{"Written by":"shajibur.rahman@interpublic.com","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/#article","isPartOf":{"@id":"https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/"},"author":{"name":"shajibur.rahman@interpublic.com","@id":"https:\/\/jp.umww.com\/en\/#\/schema\/person\/3ab450da4e035a60341554a2a939596c"},"headline":"Del Monte Names UM Philippines Media AOR","datePublished":"2017-12-21T17:21:44+00:00","dateModified":"2017-12-22T20:54:39+00:00","mainEntityOfPage":{"@id":"https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/"},"wordCount":142,"publisher":{"@id":"https:\/\/jp.umww.com\/en\/#organization"},"image":{"@id":"https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/#primaryimage"},"thumbnailUrl":"https:\/\/jp.umww.com\/wp-content\/uploads\/2017\/12\/del-monte.jpg","articleSection":["UM in the News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/","url":"https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/","name":"Del Monte Names UM Philippines Media AOR - UM JAPAN","isPartOf":{"@id":"https:\/\/jp.umww.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/#primaryimage"},"image":{"@id":"https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/#primaryimage"},"thumbnailUrl":"https:\/\/jp.umww.com\/wp-content\/uploads\/2017\/12\/del-monte.jpg","datePublished":"2017-12-21T17:21:44+00:00","dateModified":"2017-12-22T20:54:39+00:00","breadcrumb":{"@id":"https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/#primaryimage","url":"https:\/\/jp.umww.com\/wp-content\/uploads\/2017\/12\/del-monte.jpg","contentUrl":"https:\/\/jp.umww.com\/wp-content\/uploads\/2017\/12\/del-monte.jpg","width":1500,"height":844},{"@type":"BreadcrumbList","@id":"https:\/\/jp.umww.com\/en\/um-in-the-news\/del-monte-names-um-philippines-media-aor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jp.umww.com\/en\/"},{"@type":"ListItem","position":2,"name":"Del Monte Names UM Philippines Media AOR"}]},{"@type":"WebSite","@id":"https:\/\/jp.umww.com\/en\/#website","url":"https:\/\/jp.umww.com\/en\/","name":"UM JAPAN","description":"UM is a global media company.","publisher":{"@id":"https:\/\/jp.umww.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jp.umww.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/jp.umww.com\/en\/#organization","name":"UM","url":"https:\/\/jp.umww.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/jp.umww.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/jp.umww.com\/wp-content\/uploads\/2017\/11\/um-logo-transparent.png","contentUrl":"http:\/\/jp.umww.com\/wp-content\/uploads\/2017\/11\/um-logo-transparent.png","width":1378,"height":1378,"caption":"UM"},"image":{"@id":"https:\/\/jp.umww.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UMCuriosity","https:\/\/x.com\/UMWorldwide","https:\/\/www.instagram.com\/umworldwide\/","https:\/\/www.linkedin.com\/company\/um-ww\/"]},{"@type":"Person","@id":"https:\/\/jp.umww.com\/en\/#\/schema\/person\/3ab450da4e035a60341554a2a939596c","name":"shajibur.rahman@interpublic.com","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c53087da78d35d0574c041797fcd515f7503127068cd135b670ef31b05d4c151?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c53087da78d35d0574c041797fcd515f7503127068cd135b670ef31b05d4c151?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c53087da78d35d0574c041797fcd515f7503127068cd135b670ef31b05d4c151?s=96&d=mm&r=g","caption":"shajibur.rahman@interpublic.com"}}]}},"_links":{"self":[{"href":"https:\/\/jp.umww.com\/en\/wp-json\/wp\/v2\/posts\/1464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jp.umww.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jp.umww.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jp.umww.com\/en\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/jp.umww.com\/en\/wp-json\/wp\/v2\/comments?post=1464"}],"version-history":[{"count":0,"href":"https:\/\/jp.umww.com\/en\/wp-json\/wp\/v2\/posts\/1464\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jp.umww.com\/en\/wp-json\/wp\/v2\/media\/1488"}],"wp:attachment":[{"href":"https:\/\/jp.umww.com\/en\/wp-json\/wp\/v2\/media?parent=1464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jp.umww.com\/en\/wp-json\/wp\/v2\/categories?post=1464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jp.umww.com\/en\/wp-json\/wp\/v2\/tags?post=1464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}